{"id":36,"count":4,"description":"","link":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/tag\/elvis-in-the-clouds\/","name":"Elvis in The Clouds","slug":"elvis-in-the-clouds","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/tags\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/posts?tags=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}