{"id":6,"count":9,"description":"EiTC News...","link":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/eitc.elvisintheclouds.co.uk\/eitc\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}